{"id":3786,"date":"2020-12-10T14:48:32","date_gmt":"2022-01-29T03:23:24","guid":{"rendered":"https:\/\/recoverycafelexington.org\/product\/aceitunas-1\/"},"modified":"2022-01-28T22:23:24","modified_gmt":"2022-01-29T03:23:24","slug":"aceitunas-1","status":"publish","type":"product","link":"https:\/\/recoverycafelexington.org\/es\/producto\/aceitunas-1\/","title":{"rendered":"Aceitunas 1"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Deliciosas aceitunas entregadas en tu puerta. X kg incluidos en el precio por art\u00edculo.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"ddd_voice_plugin_voice_content":"","inline_featured_image":false},"product_brand":[],"product_cat":[199,205,200],"product_tag":[],"class_list":{"0":"post-3786","1":"product","2":"type-product","3":"status-publish","5":"product_cat-mercado-central-2","6":"product_cat-nombre-del-proveedor-de-aceitunas","7":"product_cat-todas-las-aceitunas","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aceitunas 1 - Recovery Caf\u00e9 Lexington<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/recoverycafelexington.org\/es\/producto\/aceitunas-1\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aceitunas 1 - Recovery Caf\u00e9 Lexington\" \/>\n<meta property=\"og:description\" content=\"Deliciosas aceitunas entregadas en tu puerta. X kg incluidos en el precio por art\u00edculo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/recoverycafelexington.org\/es\/producto\/aceitunas-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Recovery Caf\u00e9 Lexington\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/recoverycafelexington.org\\\/es\\\/producto\\\/aceitunas-1\\\/\",\"url\":\"https:\\\/\\\/recoverycafelexington.org\\\/es\\\/producto\\\/aceitunas-1\\\/\",\"name\":\"Aceitunas 1 - Recovery Caf\u00e9 Lexington\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/recoverycafelexington.org\\\/es\\\/#website\"},\"datePublished\":\"2022-01-29T03:23:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/recoverycafelexington.org\\\/es\\\/producto\\\/aceitunas-1\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/recoverycafelexington.org\\\/es\\\/producto\\\/aceitunas-1\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/recoverycafelexington.org\\\/es\\\/producto\\\/aceitunas-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/recoverycafelexington.org\\\/es\\\/casa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/recoverycafelexington.org\\\/es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aceitunas 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/recoverycafelexington.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/recoverycafelexington.org\\\/es\\\/\",\"name\":\"Recovery Caf\u00e9 Lexington\",\"description\":\"a compassionate recovery community\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/recoverycafelexington.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aceitunas 1 - Recovery Caf\u00e9 Lexington","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/recoverycafelexington.org\/es\/producto\/aceitunas-1\/","og_locale":"es_ES","og_type":"article","og_title":"Aceitunas 1 - Recovery Caf\u00e9 Lexington","og_description":"Deliciosas aceitunas entregadas en tu puerta. X kg incluidos en el precio por art\u00edculo.","og_url":"https:\/\/recoverycafelexington.org\/es\/producto\/aceitunas-1\/","og_site_name":"Recovery Caf\u00e9 Lexington","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/recoverycafelexington.org\/es\/producto\/aceitunas-1\/","url":"https:\/\/recoverycafelexington.org\/es\/producto\/aceitunas-1\/","name":"Aceitunas 1 - Recovery Caf\u00e9 Lexington","isPartOf":{"@id":"https:\/\/recoverycafelexington.org\/es\/#website"},"datePublished":"2022-01-29T03:23:24+00:00","breadcrumb":{"@id":"https:\/\/recoverycafelexington.org\/es\/producto\/aceitunas-1\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/recoverycafelexington.org\/es\/producto\/aceitunas-1\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/recoverycafelexington.org\/es\/producto\/aceitunas-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/recoverycafelexington.org\/es\/casa\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/recoverycafelexington.org\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Aceitunas 1"}]},{"@type":"WebSite","@id":"https:\/\/recoverycafelexington.org\/es\/#website","url":"https:\/\/recoverycafelexington.org\/es\/","name":"Recovery Caf\u00e9 Lexington","description":"a compassionate recovery community","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recoverycafelexington.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/recoverycafelexington.org\/es\/wp-json\/wp\/v2\/product\/3786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recoverycafelexington.org\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/recoverycafelexington.org\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/recoverycafelexington.org\/es\/wp-json\/wp\/v2\/media?parent=3786"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/recoverycafelexington.org\/es\/wp-json\/wp\/v2\/product_brand?post=3786"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/recoverycafelexington.org\/es\/wp-json\/wp\/v2\/product_cat?post=3786"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/recoverycafelexington.org\/es\/wp-json\/wp\/v2\/product_tag?post=3786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}